{"id":43,"date":"2020-05-08T16:54:58","date_gmt":"2020-05-08T16:54:58","guid":{"rendered":"https:\/\/letstshirt.it\/shop\/?page_id=43"},"modified":"2020-05-11T12:05:59","modified_gmt":"2020-05-11T12:05:59","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/letstshirt.it\/shop\/chi-siamo\/","title":{"rendered":"Chi siamo"},"content":{"rendered":"\n<p class=\"has-text-align-left wp-block-paragraph\"><strong>\u201c<\/strong>Il   marchio<strong>   <em>Let&#8217;s T-Shirt! <\/em><\/strong>   nasce   all&#8217;Isola  d&#8217;Elba   da   una   evoluzione della ditta<strong><em>\u00a0Idealpoint Multimedia<\/em>,   <\/strong>azienda grafica che nel<strong> 1996 <\/strong>si appresta ad entrare nel  campo  della  progettazione  grafica ,<strong>\u00a0\u00a0<\/strong>  spaziando  molteplici  campi  di interesse (tipografici, cartellonistici, insegne e visual communication) per poi anche specializzarsi nella personalizzazione di abbigliamento per imprese e per privati. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Let&#8217;s TShirt!  quindi  impresa artigiana ed Elbana DOC   si trasferisce  nella  sede attuale nel <strong>1998<\/strong> a <strong>Capoliveri<\/strong>, dove \u00e8 tuttora operante ed a contatto diretto non solo con aziende locali,  ma anche aziende oltre i nostri confini  e  con  migliaia  di  turisti  che  passano tutti  gli  anni  nella  nostra bellissima isola.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"475\" src=\"https:\/\/letstshirt.it\/shop\/wp-content\/uploads\/2020\/05\/externo-3-1024x475.jpg\" alt=\"\" class=\"wp-image-225\" srcset=\"https:\/\/letstshirt.it\/shop\/wp-content\/uploads\/2020\/05\/externo-3-1024x475.jpg 1024w, https:\/\/letstshirt.it\/shop\/wp-content\/uploads\/2020\/05\/externo-3-scaled-350x162.jpg 350w, https:\/\/letstshirt.it\/shop\/wp-content\/uploads\/2020\/05\/externo-3-300x139.jpg 300w, https:\/\/letstshirt.it\/shop\/wp-content\/uploads\/2020\/05\/externo-3-768x356.jpg 768w, https:\/\/letstshirt.it\/shop\/wp-content\/uploads\/2020\/05\/externo-3-1536x713.jpg 1536w, https:\/\/letstshirt.it\/shop\/wp-content\/uploads\/2020\/05\/externo-3-2048x950.jpg 2048w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ricerca<\/strong>&nbsp; e&nbsp;<strong>sperimentazione,&nbsp; flessibilit\u00e0<\/strong>&nbsp;e  prontezza  nell\u2019adeguarsi  alle  nuove esigenze di mercato, permettono di fornire&nbsp;<strong>soluzioni personalizzate<\/strong>&nbsp;ed attente ad ogni necessit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Organizzazione,&nbsp;  professionalit\u00e0  e&nbsp;  preparazione<\/strong>&nbsp;  di  tutto   il  personale  e dei collaboratori, sono i punti fondamentali della nostra filosofia commerciale.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cIl marchio Let&#8217;s T-Shirt! nasce all&#8217;Isola d&#8217;Elba da una evoluzione della ditta\u00a0Idealpoint Multimedia, azienda grafica che nel 1996 si appresta ad entrare nel campo della progettazione grafica ,\u00a0\u00a0 spaziando molteplici campi di interesse (tipografici, cartellonistici, insegne e visual communication) per poi anche specializzarsi nella personalizzazione di abbigliamento per imprese e per privati. Let&#8217;s TShirt! quindi &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/letstshirt.it\/shop\/chi-siamo\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Chi siamo&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_thinkrank_schema_form_data":"","_thinkrank_selected_schema_type":"","_thinkrank_additional_schemas":"","_thinkrank_canonical_url":"","_thinkrank_og_title":"","_thinkrank_og_description":"","_thinkrank_og_image":"","_thinkrank_twitter_title":"","_thinkrank_twitter_description":"","_thinkrank_twitter_image":"","_thinkrank_imported_from":"","_thinkrank_focus_keywords":[],"_thinkrank_focus_keyword":"","_thinkrank_robots_meta_enabled":0,"_thinkrank_robots_meta":"","_thinkrank_advanced_robots_meta":"","_thinkrank_primary_category":0,"_joinchat":[],"footnotes":""},"class_list":["post-43","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/letstshirt.it\/shop\/wp-json\/wp\/v2\/pages\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letstshirt.it\/shop\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/letstshirt.it\/shop\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/letstshirt.it\/shop\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/letstshirt.it\/shop\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":15,"href":"https:\/\/letstshirt.it\/shop\/wp-json\/wp\/v2\/pages\/43\/revisions"}],"predecessor-version":[{"id":233,"href":"https:\/\/letstshirt.it\/shop\/wp-json\/wp\/v2\/pages\/43\/revisions\/233"}],"wp:attachment":[{"href":"https:\/\/letstshirt.it\/shop\/wp-json\/wp\/v2\/media?parent=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}